{"id":295,"count":3,"description":"","link":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/","name":"hub in progress","slug":"hub-in-progress","taxonomy":"category","parent":206,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>| Associazione Socio Assistenziale dei comuni dell&#039;Acquese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hub in progress Archivi - Associazione Socio Assistenziale dei comuni dell&#039;Acquese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Socio Assistenziale dei comuni dell&#039;Acquese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/\",\"url\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/\",\"name\":\"hub in progress Archivi - Associazione Socio Assistenziale dei comuni dell&#039;Acquese\",\"isPartOf\":{\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"hub in progress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website\",\"url\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/\",\"name\":\"Associazione Socio Assistenziale dei comuni dell&#039;Acquese\",\"description\":\"ASCA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"| Associazione Socio Assistenziale dei comuni dell&#039;Acquese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/","og_locale":"it_IT","og_type":"article","og_title":"hub in progress Archivi - Associazione Socio Assistenziale dei comuni dell&#039;Acquese","og_url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/","og_site_name":"Associazione Socio Assistenziale dei comuni dell&#039;Acquese","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/","url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/","name":"hub in progress Archivi - Associazione Socio Assistenziale dei comuni dell&#039;Acquese","isPartOf":{"@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website"},"breadcrumb":{"@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/hub-in-progress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/category\/progetti\/"},{"@type":"ListItem","position":3,"name":"hub in progress"}]},{"@type":"WebSite","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website","url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/","name":"Associazione Socio Assistenziale dei comuni dell&#039;Acquese","description":"ASCA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/categories\/295"}],"collection":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/categories\/206"}],"wp:post_type":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/posts?categories=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}