{"id":1457,"date":"2018-04-26T16:59:39","date_gmt":"2018-04-26T14:59:39","guid":{"rendered":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/?p=1457"},"modified":"2020-11-11T15:07:59","modified_gmt":"2020-11-11T14:07:59","slug":"inaugurato-primo-alzhiemer-cafe-del-territorio","status":"publish","type":"post","link":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/","title":{"rendered":"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio"},"content":{"rendered":"<p>il \u00a0giorno <strong>marted\u00ec 24 aprile alle ore 14:30<\/strong> \u00e8 stato\u00a0inaugurato\u00a0il\u00a0 primo Alzheimer \u00a0Caf\u00e8 del territorio acquese.<\/p>\n<p>All&#8217;incontro, che\u00a0 si\u00a0 \u00e8 tenuto presso locali\u00a0 della <strong>Mensa della Fraternit\u00e0 in via Cassino 27 &#8211; Acqui Terme (ex-Ricre),<\/strong>\u00a0 sono intervenute le\u00a0autorit\u00e0 laiche e religiose del territorio:\u00a0 il vescovo Mons Luigi Testore e il Presidente Caritas Don Luigi Falchero,\u00a0 il sindaco Lorenzo Lucchini e l&#8217;assessore alle politiche sociali Alessandra Terzolo,\u00a0 i responsabili dell&#8217;ASCA oltre alle rappresentanze di tutti i partner.<\/p>\n<p>L&#8217;attivit\u00e0 nasce all&#8217;interno di un progetto pi\u00f9 ampio rivolto agli anziani: Progetto S.M.A.R.T. (Scherzi della Memoria Anziani e Riabilitazione Territoriale), promosso dall&#8217;ASCA\u00a0in collaborazione con una molteplicit\u00e0 di partner ed \u00e8 sostenuto dalla Compagnia di San Paolo.<\/p>\n<p>Le attivit\u00e0 dell\u2019Alzheimer\u00a0 Caf\u00e8\u00a0sono rese\u00a0 possibili grazie all&#8217;impegno di numerosi volontari e alla disponibilit\u00e0 della Caritas che ha messo a disposizione i locali della Mensa della Fraternit\u00e0<a href=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1465\" src=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp\" alt=\"\" width=\"1550\" height=\"1550\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>RASSEGNA STAMPA<\/strong><\/h2>\n<h3><strong>LA STAMPA<\/strong><\/h3>\n<p><a href=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/inaugurazione_lastampa.bmp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1468\" src=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/inaugurazione_lastampa.bmp\" alt=\"\" width=\"696\" height=\"1427\" \/><\/a><\/p>\n<h3><strong>L&#8217;ANCORA<\/strong><\/h3>\n<p><a href=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/inaugurazione_ancora.bmp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1469\" src=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/inaugurazione_ancora.bmp\" alt=\"\" width=\"678\" height=\"752\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>il \u00a0giorno marted\u00ec 24 aprile alle ore 14:30 \u00e8 stato\u00a0inaugurato\u00a0il\u00a0 primo Alzheimer \u00a0Caf\u00e8 del territorio acquese. All&#8217;incontro, che\u00a0 si\u00a0 \u00e8 tenuto presso locali\u00a0 della Mensa della Fraternit\u00e0 in via Cassino 27 &#8211; Acqui Terme (ex-Ricre),\u00a0 sono intervenute le\u00a0autorit\u00e0 laiche e religiose del territorio:\u00a0 il vescovo Mons Luigi Testore e il Presidente Caritas Don Luigi Falchero,\u00a0&hellip; <a class=\"continue\" href=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/\">Continua a leggere<span> Inaugurato il primo Alzhiemer Caf\u00e8 del territorio<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[195,205,206,1,204],"tags":[223,217,284,282,283],"class_list":["post-1457","post","type-post","status-publish","format-standard","hentry","category-anziani","category-notizie-ed-eventi","category-progetti","category-senza-categoria","category-servizi-per-tutti","tag-alzheimer","tag-anziani","tag-caffe","tag-demenze","tag-ricre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inaugurato il primo Alzhiemer Caf\u00e8 del territorio | Associazione Socio Assistenziale dei comuni dell&#039;Acquese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio - Associazione Socio Assistenziale dei comuni dell&#039;Acquese\" \/>\n<meta property=\"og:description\" content=\"il \u00a0giorno marted\u00ec 24 aprile alle ore 14:30 \u00e8 stato\u00a0inaugurato\u00a0il\u00a0 primo Alzheimer \u00a0Caf\u00e8 del territorio acquese. All&#8217;incontro, che\u00a0 si\u00a0 \u00e8 tenuto presso locali\u00a0 della Mensa della Fraternit\u00e0 in via Cassino 27 &#8211; Acqui Terme (ex-Ricre),\u00a0 sono intervenute le\u00a0autorit\u00e0 laiche e religiose del territorio:\u00a0 il vescovo Mons Luigi Testore e il Presidente Caritas Don Luigi Falchero,\u00a0&hellip; Continua a leggere Inaugurato il primo Alzhiemer Caf\u00e8 del territorio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Socio Assistenziale dei comuni dell&#039;Acquese\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-26T14:59:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-11T14:07:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp\" \/>\n<meta name=\"author\" content=\"Asca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Asca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/\",\"url\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/\",\"name\":\"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio - Associazione Socio Assistenziale dei comuni dell&#039;Acquese\",\"isPartOf\":{\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp\",\"datePublished\":\"2018-04-26T14:59:39+00:00\",\"dateModified\":\"2020-11-11T14:07:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#\/schema\/person\/f0a9aff3e4bbd22511d3556b6b28f9df\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#primaryimage\",\"url\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp\",\"contentUrl\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp\",\"width\":1550,\"height\":1550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website\",\"url\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/\",\"name\":\"Associazione Socio Assistenziale dei comuni dell&#039;Acquese\",\"description\":\"ASCA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#\/schema\/person\/f0a9aff3e4bbd22511d3556b6b28f9df\",\"name\":\"Asca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5a8e08b9d65c9f8348c2e2db3ff2654c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5a8e08b9d65c9f8348c2e2db3ff2654c?s=96&d=mm&r=g\",\"caption\":\"Asca\"},\"url\":\"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/author\/asca\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio | Associazione Socio Assistenziale dei comuni dell&#039;Acquese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/","og_locale":"it_IT","og_type":"article","og_title":"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio - Associazione Socio Assistenziale dei comuni dell&#039;Acquese","og_description":"il \u00a0giorno marted\u00ec 24 aprile alle ore 14:30 \u00e8 stato\u00a0inaugurato\u00a0il\u00a0 primo Alzheimer \u00a0Caf\u00e8 del territorio acquese. All&#8217;incontro, che\u00a0 si\u00a0 \u00e8 tenuto presso locali\u00a0 della Mensa della Fraternit\u00e0 in via Cassino 27 &#8211; Acqui Terme (ex-Ricre),\u00a0 sono intervenute le\u00a0autorit\u00e0 laiche e religiose del territorio:\u00a0 il vescovo Mons Luigi Testore e il Presidente Caritas Don Luigi Falchero,\u00a0&hellip; Continua a leggere Inaugurato il primo Alzhiemer Caf\u00e8 del territorio","og_url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/","og_site_name":"Associazione Socio Assistenziale dei comuni dell&#039;Acquese","article_published_time":"2018-04-26T14:59:39+00:00","article_modified_time":"2020-11-11T14:07:59+00:00","og_image":[{"url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp","type":"","width":"","height":""}],"author":"Asca","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Asca","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/","url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/","name":"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio - Associazione Socio Assistenziale dei comuni dell&#039;Acquese","isPartOf":{"@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#primaryimage"},"image":{"@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp","datePublished":"2018-04-26T14:59:39+00:00","dateModified":"2020-11-11T14:07:59+00:00","author":{"@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#\/schema\/person\/f0a9aff3e4bbd22511d3556b6b28f9df"},"breadcrumb":{"@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#primaryimage","url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp","contentUrl":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-content\/uploads\/2018\/04\/info-per-sito.bmp","width":1550,"height":1550},{"@type":"BreadcrumbList","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/inaugurato-primo-alzhiemer-cafe-del-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/"},{"@type":"ListItem","position":2,"name":"Inaugurato il primo Alzhiemer Caf\u00e8 del territorio"}]},{"@type":"WebSite","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#website","url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/","name":"Associazione Socio Assistenziale dei comuni dell&#039;Acquese","description":"ASCA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#\/schema\/person\/f0a9aff3e4bbd22511d3556b6b28f9df","name":"Asca","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5a8e08b9d65c9f8348c2e2db3ff2654c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a8e08b9d65c9f8348c2e2db3ff2654c?s=96&d=mm&r=g","caption":"Asca"},"url":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/author\/asca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/posts\/1457"}],"collection":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/comments?post=1457"}],"version-history":[{"count":5,"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/posts\/1457\/revisions"}],"predecessor-version":[{"id":1470,"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/posts\/1457\/revisions\/1470"}],"wp:attachment":[{"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/media?parent=1457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/categories?post=1457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unionemontanasuoldaleramo.it\/asca\/wp-json\/wp\/v2\/tags?post=1457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}